{"id":2551,"count":1,"description":"","link":"https:\/\/larya.com.br\/blog\/tag\/transacao-imobiliaria\/","name":"transa\u00e7\u00e3o imobili\u00e1ria","slug":"transacao-imobiliaria","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/larya.com.br\/blog\/wp-json\/wp\/v2\/tags\/2551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larya.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/larya.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/larya.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=2551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}